{"id":3551,"date":"2024-03-27T05:10:00","date_gmt":"2024-03-27T08:10:00","guid":{"rendered":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/"},"modified":"2024-03-28T10:15:57","modified_gmt":"2024-03-28T13:15:57","slug":"conselho-deliberativo-do-sindiextra-se-reune-na-fiemg","status":"publish","type":"noticias","link":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/","title":{"rendered":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Conselho Deliberativo do Sindicato da Ind\u00fastria Mineral do Estado de Minas Gerais (Sindiextra) se reuniu, no dia 27 de mar\u00e7o, na sede da FIEMG, em Belo Horizonte. \u201cO colegiado \u00e9 composto por 20 integrantes, que s\u00e3o representantes das principais empresas mineradoras do estado\u201d, explica Lu\u00eds M\u00e1rcio Vianna, presidente do sindicato, na abertura do evento, esclarecendo que o Conselho Deliberativo atua na formula\u00e7\u00e3o das pol\u00edticas da entidade e na maneira como ela se relaciona com os poderes p\u00fablicos, com os demais sindicatos, com a FIEMG e a CNI, dentre outras institui\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg\" alt=\"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG\" class=\"wp-image-3552\" style=\"width:384px;height:auto\" srcset=\"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg 512w, https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb-300x300.jpeg 300w, https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb-150x150.jpeg 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Vianna, entre as atividades permanentes do Sindiextra est\u00e3o as reuni\u00f5es mensais com os grupos de trabalhos de Meio Ambiente e Sustentabilidade, Inova\u00e7\u00e3o e Tecnologia e \u201cMinera\u00e7\u00e3o de Minas Gerais Portadora de Futuro\u201d. Tamb\u00e9m fazem parte do escopo de atua\u00e7\u00e3o o alinhamento com a FIEMG para presta\u00e7\u00e3o de consultorias Ambiental, Econ\u00f4mica, Trabalhista, Tribut\u00e1ria, Tecnol\u00f3gica e de Comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o segundo semestre de 2024, est\u00e1 no planejamento do sindicato a presen\u00e7a na edi\u00e7\u00e3o de 2024 do Pr\u00eamio Hugo Werneck, as participa\u00e7\u00f5es nas miss\u00f5es empresariais Exponor do Chile e Uni\u00e3o Europeia, em Belo Horizonte. Tamb\u00e9m ser\u00e3o realizados os eventos Minera\u00e7\u00e3o &amp;\/X Comunidades, e as Melhores Mineradoras, com a Brasil Mineral e o Encontro Anual dos Produtores de Agregados da Constru\u00e7\u00e3o Civil, entre outras atividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A reuni\u00e3o do Conselho Deliberativo do Sindiextra foi presidida por Jos\u00e9 Fernando Coura, presidente do Colegiado, e contou com as apresenta\u00e7\u00f5es de Lauro Amorim, diretor executivo da Vale, e Rodrigo Franco, presidente da Funda\u00e7\u00e3o Estadual de Meio Ambiente (FEAM).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Franco apresentou as compet\u00eancias da FEAM e as novidades p\u00f3s segunda reforma administrativa proporcionada pelo Governo Estadual. \u201cO licenciamento ambiental est\u00e1 conosco agora, e estamos com uma equipe espec\u00edfica nessa agenda, e as compet\u00eancias das barragens de rejeitos de minera\u00e7\u00e3o industrial, fechamento de minas e \u00e1reas contaminadas. S\u00e3o temas sens\u00edveis para o estado e que pertencem a nossa pasta\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 Amorim, apresentou os principais n\u00fameros da empresa Vale em Minas Gerais. \u201cAtualmente geramos mais de 30 mil empregos diretos e 26 mil indiretos. Nossa produ\u00e7\u00e3o anual \u00e9 de 125 milh\u00f5es de min\u00e9rio de ferro, e a proje\u00e7\u00e3o para at\u00e9 2028 \u00e9 de 145 milh\u00f5es de toneladas&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o diretor executivo da Vale, Minas Gerais tem import\u00e2ncia central para a empresa. \u201cTemos uma estrat\u00e9gia clara de descarboniza\u00e7\u00e3o e, para isso, precisamos de min\u00e9rio de qualidade. Devido a sua pr\u00f3pria natureza, o estado possui grandes minas e estamos trazendo isso o cerne da descarboniza\u00e7\u00e3o. Al\u00e9m de minerais de transi\u00e7\u00e3o energ\u00e9tica, o min\u00e9rio de ferro, abundante no estado, \u00e9 de suma import\u00e2ncia neste processo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-flickr wp-block-embed-flickr\"><div class=\"wp-block-embed__wrapper\">\n<a data-flickr-embed='true' href='https:\/\/www.flickr.com\/photos\/sistemafiemg\/albums\/72177720315719011\/' title='270324 Assembleia Ordin\u00e1ria Geral e Encontro do Conselho Deliberativo SINDIEXTRA by FIEMGoficial, on Flickr'><img src='https:\/\/live.staticflickr.com\/65535\/53615296435_043c51b72d_c.jpg' width='800' height='600' alt='SJJ_2489'><\/a><script async src='https:\/\/embedr.flickr.com\/assets\/client-code.js' charset='utf-8'><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><em>Denise Lucas<br><\/em><strong>Imprensa FIEMG<\/strong><\/p>\n","protected":false},"featured_media":3552,"template":"","categories":[15],"tags":[91,78,104,85],"class_list":["post-3551","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","category-desenvolvimento-industrial","tag-conselho","tag-fiemg","tag-industria","tag-sindiextra"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG<\/title>\n<meta name=\"description\" content=\"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG\" \/>\n<meta property=\"og:description\" content=\"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/\" \/>\n<meta property=\"og:site_name\" content=\"FIEMG\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T13:15:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/\",\"name\":\"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2024\\\/03\\\/sindextra_thumb.jpeg\",\"datePublished\":\"2024-03-27T08:10:00+00:00\",\"dateModified\":\"2024-03-28T13:15:57+00:00\",\"description\":\"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2024\\\/03\\\/sindextra_thumb.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2024\\\/03\\\/sindextra_thumb.jpeg\",\"width\":512,\"height\":512,\"caption\":\"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/noticias\\\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#website\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/\",\"name\":\"FIEMG\",\"description\":\"Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Minas Gerais\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#organization\",\"name\":\"FIEMG\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/fiemg_branco.svg\",\"contentUrl\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/fiemg_branco.svg\",\"width\":561,\"height\":147,\"caption\":\"FIEMG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/fiemg\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG","description":"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/","og_locale":"pt_BR","og_type":"article","og_title":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG","og_description":"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM","og_url":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/","og_site_name":"FIEMG","article_modified_time":"2024-03-28T13:15:57+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/","url":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/","name":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG - FIEMG","isPartOf":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/#primaryimage"},"image":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg","datePublished":"2024-03-27T08:10:00+00:00","dateModified":"2024-03-28T13:15:57+00:00","description":"Encontro contou com as presen\u00e7as de representantes da empresa Vale e da FEAM","breadcrumb":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/#primaryimage","url":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg","contentUrl":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2024\/03\/sindextra_thumb.jpeg","width":512,"height":512,"caption":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiemg.com.br\/fiemg\/noticias\/conselho-deliberativo-do-sindiextra-se-reune-na-fiemg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fiemg.com.br\/fiemg\/"},{"@type":"ListItem","position":2,"name":"Conselho Deliberativo do Sindiextra se re\u00fane na FIEMG"}]},{"@type":"WebSite","@id":"https:\/\/www.fiemg.com.br\/fiemg\/#website","url":"https:\/\/www.fiemg.com.br\/fiemg\/","name":"FIEMG","description":"Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Minas Gerais","publisher":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiemg.com.br\/fiemg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.fiemg.com.br\/fiemg\/#organization","name":"FIEMG","url":"https:\/\/www.fiemg.com.br\/fiemg\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.fiemg.com.br\/fiemg\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2023\/02\/fiemg_branco.svg","contentUrl":"https:\/\/www.fiemg.com.br\/fiemg\/wp-content\/uploads\/sites\/10\/2023\/02\/fiemg_branco.svg","width":561,"height":147,"caption":"FIEMG"},"image":{"@id":"https:\/\/www.fiemg.com.br\/fiemg\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/noticias\/3551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/types\/noticias"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/media\/3552"}],"wp:attachment":[{"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/media?parent=3551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/categories?post=3551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiemg.com.br\/fiemg\/wp-json\/wp\/v2\/tags?post=3551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}