{"id":137,"count":1,"description":"","link":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/","name":"Mercado de Trabalho","slug":"mercado-de-trabalho","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Regional Vale do a\u00e7o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/tag\\\/mercado-de-trabalho\\\/\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/tag\\\/mercado-de-trabalho\\\/\",\"name\":\"Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/tag\\\/mercado-de-trabalho\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/tag\\\/mercado-de-trabalho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado de Trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#website\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/\",\"name\":\"Regional Vale do a\u00e7o\",\"description\":\"Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Minas Gerais\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#organization\",\"name\":\"Regional Vale do a\u00e7o\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/02\\\/Ativo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/02\\\/Ativo-1.png\",\"width\":563,\"height\":149,\"caption\":\"Regional Vale do a\u00e7o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fiemg.com.br\\\/regional-vale-do-aco\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o","og_url":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/","og_site_name":"Regional Vale do a\u00e7o","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/","url":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/","name":"Arquivo de Mercado de Trabalho - Regional Vale do a\u00e7o","isPartOf":{"@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#website"},"breadcrumb":{"@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/tag\/mercado-de-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/"},{"@type":"ListItem","position":2,"name":"Mercado de Trabalho"}]},{"@type":"WebSite","@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#website","url":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/","name":"Regional Vale do a\u00e7o","description":"Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Minas Gerais","publisher":{"@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#organization","name":"Regional Vale do a\u00e7o","url":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-content\/uploads\/sites\/22\/2023\/02\/Ativo-1.png","contentUrl":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-content\/uploads\/sites\/22\/2023\/02\/Ativo-1.png","width":563,"height":149,"caption":"Regional Vale do a\u00e7o"},"image":{"@id":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/tags\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/posts?tags=137"},{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/area-de-interesse?tags=137"},{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/destaques?tags=137"},{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/noticias?tags=137"},{"href":"https:\/\/www.fiemg.com.br\/regional-vale-do-aco\/wp-json\/wp\/v2\/produtos?tags=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}